{"id":328,"count":1,"description":"","link":"https:\/\/staging-live.lbpost.com\/hi-lo\/tag\/sponsored-by-long-beach-comic-con\/","name":"sponsored by long beach comic con","slug":"sponsored-by-long-beach-comic-con","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/staging-live.lbpost.com\/hi-lo\/wp-json\/wp\/v2\/tags\/328"}],"collection":[{"href":"https:\/\/staging-live.lbpost.com\/hi-lo\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/staging-live.lbpost.com\/hi-lo\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/staging-live.lbpost.com\/hi-lo\/wp-json\/wp\/v2\/posts?tags=328"},{"href":"https:\/\/staging-live.lbpost.com\/hi-lo\/wp-json\/wp\/v2\/newspack_spnsrs_cpt?tags=328"},{"href":"https:\/\/staging-live.lbpost.com\/hi-lo\/wp-json\/wp\/v2\/newspack_nl_cpt?tags=328"},{"href":"https:\/\/staging-live.lbpost.com\/hi-lo\/wp-json\/wp\/v2\/newspack_popups_cpt?tags=328"},{"href":"https:\/\/staging-live.lbpost.com\/hi-lo\/wp-json\/wp\/v2\/tribe_events?tags=328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}