{"id":1551,"count":3,"description":"","link":"https:\/\/staging-live.lbpost.com\/hi-lo\/tag\/long-beach-noir\/","name":"Long beach noir","slug":"long-beach-noir","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/staging-live.lbpost.com\/hi-lo\/wp-json\/wp\/v2\/tags\/1551"}],"collection":[{"href":"https:\/\/staging-live.lbpost.com\/hi-lo\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/staging-live.lbpost.com\/hi-lo\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/staging-live.lbpost.com\/hi-lo\/wp-json\/wp\/v2\/posts?tags=1551"},{"href":"https:\/\/staging-live.lbpost.com\/hi-lo\/wp-json\/wp\/v2\/newspack_spnsrs_cpt?tags=1551"},{"href":"https:\/\/staging-live.lbpost.com\/hi-lo\/wp-json\/wp\/v2\/newspack_nl_cpt?tags=1551"},{"href":"https:\/\/staging-live.lbpost.com\/hi-lo\/wp-json\/wp\/v2\/newspack_popups_cpt?tags=1551"},{"href":"https:\/\/staging-live.lbpost.com\/hi-lo\/wp-json\/wp\/v2\/tribe_events?tags=1551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}